{"id":4036,"date":"2015-12-01T23:14:07","date_gmt":"2015-12-01T22:14:07","guid":{"rendered":"https:\/\/ideiasdafia.pt\/?p=4036"},"modified":"2019-08-30T22:17:01","modified_gmt":"2019-08-30T22:17:01","slug":"descobertas-de-novembro","status":"publish","type":"post","link":"https:\/\/ideiasdafia.pt\/en\/descobertas-de-novembro\/","title":{"rendered":"As descobertas de Novembro"},"content":{"rendered":"<p>E chegou o momento de mais uma partilha de descobertas.<\/p>\n<div class=\"ast-oembed-container\" style=\"height: 100%;\"><iframe title=\"Descobertas de Novembro (dicas)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/z7OO3L-1y3Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><strong>Produtos<\/strong><\/p>\n<p>Este m\u00eas experimentei finalmente o doseador de pasta dent\u00edfrica que mandei vir da china e funciona que \u00e9 um brinco. Assim como j\u00e1 est\u00e1 instalado no arm\u00e1rio o suporte para organizar e proteger as escovas de dentes. At\u00e9 aqui tudo a favor.<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro8.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-4047 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro8.jpg\" alt=\"descobertas_novembro8\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p>Entretanto, experimentei o amaciador Doussy do Lidl e descobri que n\u00e3o gosto do resultado e que n\u00e3o volto a comprar. Cheira bem do frasco, mas p\u00f3s roupa lavada \u00e9 demasiado intenso. Sei l\u00e1, n\u00e3o gosto. J\u00e1 o dei a algu\u00e9m que gostou do cheiro.<\/p>\n<p>H\u00e1-de chegar o dia em que usarei um cheirinho mais natural e n\u00e3o-t\u00f3xico. Por enquanto gosto dos amaciadores SAN.<\/p>\n<p><strong>Comida<\/strong><\/p>\n<p>No que toca a comida, experimentei (pela terceira ou quarta vez) manteiga de amendoim e (desta vez) gostei. Parece-me que a grande diferen\u00e7a consiste na forma como a experimentei, desta vez e nas anteriores. Antes tinha experimentado com p\u00e3o &#8211; <em>blargh!<\/em> &#8211; e agora foi s\u00f3 com fruta &#8211; <em>yum!<\/em><\/p>\n<p>Basicamente, corto a ma\u00e7\u00e3 \u00e0s rodelas e fa\u00e7o sandu\u00edches de ma\u00e7\u00e3 e manteiga de amendoim. E, na minha vers\u00e3o preferida, corto uma banana ao meio e longitudinalmente, e barro as metades com manteiga de amendoim. Decadente, mas absolutamente delicioso. Posso dizer que s\u00f3 em Novembro foram 4 frascos! Um exagero, bem sei. Mencionei decadente?<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro14.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-4057 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro14.jpg\" alt=\"descobertas_novembro14\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p>Mas tamb\u00e9m experimentei, finalmente, as famosas bolachas de aveia e banana. Uma del\u00edcia sem gl\u00faten, sem lactose e sem a\u00e7ucares adicionados. Se quiser que partilhe a receita com imagem (foto e video), \u00e9 s\u00f3 deixar um coment\u00e1rio a indic\u00e1-lo.<\/p>\n<p>Resumidamente, levam 3 ingredientes: aveia (sem gl\u00faten), banana e mel. Pessoalmente, gosto ainda de lhes juntar passas e, no final, uns flocos de aveia tufados em cima, mas \u00e9 a gosto.<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro2.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-4041 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro2.jpg\" alt=\"descobertas_novembro2\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p><strong>Canais de YouTube<\/strong><\/p>\n<p>Entre os canais de YouTube que descobri este m\u00eas e que gostei, passei a seguir estes:<\/p>\n<ul type=\"disc\">\n<li><a href=\"https:\/\/www.youtube.com\/channel\/UCKfSNB-aBP1IOCzW1LUn8_g\" target=\"_blank\" rel=\"noopener noreferrer\">Amanda Morbeck<\/a>&nbsp;com videos muito bons de reforma da casa<\/li>\n<li><a href=\"https:\/\/www.youtube.com\/channel\/UCkodM4DHUloJMgRjku7r_Vg\" target=\"_blank\" rel=\"noopener noreferrer\">Fablunch<\/a>&nbsp;sobre comida saud\u00e1vel<\/li>\n<li><a href=\"https:\/\/www.youtube.com\/channel\/UCuDufvMqARdu9zPPkQEWJUw\" target=\"_blank\" rel=\"noopener noreferrer\">Kaka Kraft<\/a>&nbsp;com tutoriais para quem gosta de jogos de computador<\/li>\n<li><a href=\"https:\/\/www.youtube.com\/channel\/UCAhe-slHtLFlWEHWKKmIvdg\" target=\"_blank\" rel=\"noopener noreferrer\">Nah Cardoso<\/a>&nbsp;com videos de tutoriais e de beleza<\/li>\n<li><a href=\"https:\/\/www.youtube.com\/channel\/UC87V8rZPwCmQUP2ug5ND-TA\" target=\"_blank\" rel=\"noopener noreferrer\">Paula Steph\u00e2nia<\/a>&nbsp;com decora\u00e7\u00f5es em casa, delicadas e lindas<\/li>\n<\/ul>\n<p><strong>Apps <\/strong>(para iOS)<\/p>\n<p>Estou ainda a explorar duas apps que descobri este m\u00eas e me parece valer a pena a refer\u00eancia:<\/p>\n<p>Calendarique &#8211; um widget para apresentar o calend\u00e1rio no centro de notifica\u00e7\u00f5es e barra de menu (como a imagem abaixo indica). Permite organizar as marca\u00e7\u00f5es por cor e a apresenta\u00e7\u00e3o \u00e9 mais bonitinha.<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4050 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro11.jpg\" alt=\"descobertas_novembro11\" width=\"500\" height=\"313\" title=\"\"><\/a><\/p>\n<p>E dSurvival &#8211; uma esp\u00e9cie de canivete su\u00ed\u00e7o de apps para sobreviv\u00eancia que oferece desde b\u00fassola a kit de GPS, passando por kit de c\u00f3digo morse, lanterna, medidor de inclina\u00e7\u00e3o do terreno, de \u00e2ngulos ou de microTesla, sism\u00f3metro ou bolha de n\u00edvel (entre outros).<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4051 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro12.jpg\" alt=\"descobertas_novembro12\" width=\"500\" height=\"888\" title=\"\"><\/a><\/p>\n<p><strong>Curiosidades<\/strong><\/p>\n<p>Numa categoria gen\u00e9rica, descobri outras coisas interessantes. Por exemplo, (re)descobri que fazer pequenas repara\u00e7\u00f5es, que aguardam h\u00e1 muito, num espa\u00e7o da casa, pode melhorar muito o seu uso no dia-a-dia.<\/p>\n<p>Este m\u00eas na cozinha, a janela ganhou uma cortina,<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4042 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro3.jpg\" alt=\"descobertas_novembro3\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p>a pega do forno foi reparada,<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4046 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro7.jpg\" alt=\"descobertas_novembro7\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p>as gavetas voltaram a deslizar com novas calhas e rod\u00edzios<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4043 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro4.jpg\" alt=\"descobertas_novembro4\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p>e os arm\u00e1rios ganharam pratos novos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4052\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro13.jpg\" alt=\"descobertas_novembro13\" width=\"500\" height=\"375\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>V\u00ea aqueles pratos laranjinha, que combinam t\u00e3o bem com a parede amarela? S\u00e3o esses. E agora tamb\u00e9m combinam muito bem com a zona de refei\u00e7\u00f5es no exterior, em frente \u00e0 cozinha.<\/p>\n<p>\u00c9 que esta foi mais uma descoberta. Uma necessidade levou a uma mudan\u00e7a e uma mudan\u00e7a levou a outra, entretanto, temos uma zona completamente nova no exterior. Mas como ainda n\u00e3o est\u00e1 terminada, em breve mostro os detalhes, com <a href=\"https:\/\/ideiasdafia.pt\/en\/parede-grande-em-branco-no-jardim\/\">o antes e o depois<\/a>.<\/p>\n<p>Mas posso levantar um bocadinho o v\u00e9u do durante&#8230;<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4045 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro6.jpg\" alt=\"descobertas_novembro6\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4044 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro5.jpg\" alt=\"descobertas_novembro5\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p>Mas nesta foto j\u00e1 d\u00e1 para antever alguns detalhes&#8230;<\/p>\n<p><a href=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4049 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro10.jpg\" alt=\"descobertas_novembro10\" width=\"500\" height=\"375\" title=\"\"><\/a><\/p>\n<p>E estou mesmo a gostar da minha cortina nova! \ud83d\ude42 (com exclama\u00e7\u00e3o e <em>smiley<\/em>, s\u00f3 para matar saudades)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4048 size-full\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/12\/descobertas_novembro9.jpg\" alt=\"descobertas_novembro9\" width=\"500\" height=\"375\" title=\"\"><\/p>\n<p><strong>Gosta da minha &#8220;janela nova&#8221;?<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>E chegou o momento de mais uma partilha de descobertas. Produtos Este m\u00eas experimentei finalmente o doseador de pasta dent\u00edfrica que mandei vir da china e funciona que \u00e9 um brinco. Assim como j\u00e1 est\u00e1 instalado no arm\u00e1rio o suporte para organizar e proteger as escovas de dentes. At\u00e9 aqui tudo a favor. Entretanto, experimentei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[45],"tags":[39,126,130,127,4,131],"class_list":["post-4036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","tag-ca-de-casa","tag-canais-youtube","tag-casa","tag-descobertas-do-mes","tag-dicas","tag-quintal"],"_links":{"self":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/4036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/comments?post=4036"}],"version-history":[{"count":0,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/4036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media\/9481"}],"wp:attachment":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media?parent=4036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/categories?post=4036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/tags?post=4036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}