{"id":3800,"date":"2015-09-23T15:57:53","date_gmt":"2015-09-23T14:57:53","guid":{"rendered":"https:\/\/ideiasdafia.pt\/?p=3800"},"modified":"2019-08-30T22:14:12","modified_gmt":"2019-08-30T22:14:12","slug":"11-dicas-para-compras-da-china","status":"publish","type":"post","link":"https:\/\/ideiasdafia.pt\/en\/11-dicas-para-compras-da-china\/","title":{"rendered":"11 Dicas para compras da China"},"content":{"rendered":"<p>Sabe aqueles sites de produtos que v\u00eam da China, com pre\u00e7os mais curtos que a mini saia? Hoje trago 11 dicas para partilhar consigo sobre como pode (tamb\u00e9m) poupar nestas encomendas.<\/p>\n<p>Tanto podemos poupar reduzindo o pre\u00e7o de custo na hora da compra, quanto reduzindo custos (e chatices) a curto e m\u00e9dio prazo. Refiro-me a ambos.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Compras da China: 11 Dicas para comprar (parte 1 de 2)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/OjByTJ_xnEI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>N\u00e3o que eu seja especialista no assunto porque at\u00e9 hoje s\u00f3 fiz 3 destas encomendas, mas porque s\u00e3o detalhes que facilmente descuramos por estarmos habituados a comprar artigos de uma forma diferente. Detalhes que fazem toda a diferen\u00e7a.<\/p>\n<p><strong>1 &#8211; Leia os coment\u00e1rios de quem j\u00e1 comprou<\/strong><\/p>\n<p>Embora possa encontrar muitos coment\u00e1rios infundados (porque se encontram de todos os tipos) ou referentes a situa\u00e7\u00f5es singulares, tamb\u00e9m pode encontrar muita informa\u00e7\u00e3o \u00fatil sobre a venda em si.<\/p>\n<p>O que j\u00e1 aprendi ao ler os coment\u00e1rios:<\/p>\n<ul>\n<li>que alguns artigos s\u00e3o vendidos em partes distintas (exemplo: emissor e receptor em separado, quando quer comprar o conjunto)<\/li>\n<li>que determinados acess\u00f3rios s\u00e3o vendidos \u00e0 parte<\/li>\n<li>que \u00e9 preciso ter muito cuidado com as medidas<\/li>\n<li>que o artigo el\u00e9ctrico pode vir com ficha para tomadas da Europa ou dos EUA<\/li>\n<\/ul>\n<p>Informa\u00e7\u00f5es que poderiam estar claras na descri\u00e7\u00e3o (que eu n\u00e3o li por completo) ou n\u00e3o.<\/p>\n<p><strong>2 &#8211; Avalie as queixas nos coment\u00e1rios<\/strong><\/p>\n<p>Digo isto porque, como disse, encontramos todo o tipo de coment\u00e1rios e porque h\u00e1 muita gente &#8211; <em>ahem <\/em>&#8211; que n\u00e3o l\u00ea toda a descri\u00e7\u00e3o do artigo e depois queixa-se sem raz\u00e3o. De forma que conv\u00e9m comparar a informa\u00e7\u00e3o dos coment\u00e1rios com a descri\u00e7\u00e3o e as fotografias do artigo para ver se as queixas lhe parecem fundadas.<\/p>\n<p>Claro que me posso enganar, mas parece-me t\u00e3o claro o motivo de tantos dos coment\u00e1rios que ali deixam&#8230;<\/p>\n<p>Como exemplo, que partilhei no video acima, ao encomendar um carregador sem fios para o telem\u00f3vel, li coment\u00e1rios de uns que diziam que n\u00e3o funcionava e de outros que diziam que era um espect\u00e1culo e fazia o que tinha sido anunciado.<\/p>\n<p>Ao voltar a ler a descri\u00e7\u00e3o, vi a informa\u00e7\u00e3o de que o artigo em quest\u00e3o era apenas o emissor para carregar o telem\u00f3vel, mas que precisaria de comprar tamb\u00e9m o receptor para que funcionasse.<\/p>\n<p>Conclus\u00e3o: metade daqueles compradores n\u00e3o tinha (tal como eu) lido a descri\u00e7\u00e3o na \u00edntegra. E para al\u00e9m de pensarem que o artigo que compraram n\u00e3o funciona (e terem deixado um feedback negativo para a loja e outros interessados), alguns deles provavelmente far\u00e3o nova compra de outra loja e voltar\u00e3o a cair no mesmo erro.<\/p>\n<p>Mas tamb\u00e9m poder\u00e1 encontrar informa\u00e7\u00e3o sobre defeitos nas pe\u00e7as ou a sua qualidade, que podem ajudar na decis\u00e3o de compra.<\/p>\n<p><strong>3 &#8211; Veja todas as fotografias do artigo<\/strong><\/p>\n<p>Inclusive, e especialmente, as fotografias tiradas pelos compradores, ap\u00f3s receberem os seus produtos.<\/p>\n<p>Dependendo do site e\/ou app que utilizar, os compradores poder\u00e3o ter a possibilidade de tirar uma fotografia com o seu telem\u00f3vel e envi\u00e1-la no momento do feedback sobre o produto e a loja. Isto ajuda a loja as suas pr\u00f3prias imagens e artigos.<\/p>\n<p><strong>4 &#8211; Amplie as fotografias&nbsp;<\/strong><\/p>\n<p>Abra a fotografia do artigo em que este esteja mais pr\u00f3ximo (maior) e amplie-a para ver melhor a qualidade do material.<\/p>\n<p>D\u00e1 para ver avaliar a transpar\u00eancia, espessura, tipo de material, trama do tecido, etc.<\/p>\n<p><strong>5 &#8211; Verifique as medidas<\/strong><\/p>\n<p>Pegue na fita m\u00e9trica e procure as tabelas de medidas do artigo ou de compara\u00e7\u00e3o de medidas entre pa\u00edses. Pode evitar assim muitas chatices.<\/p>\n<p><strong>6 &#8211; Tenha aten\u00e7\u00e3o ao valor dos portes<\/strong><\/p>\n<p>Porque algumas lojas oferecem os portes, outras cobram apenas 1 ou 2 euros, mas outras baixam o pre\u00e7o do artigo para atrair interessados e colocam a diferen\u00e7a no valor do envio.<\/p>\n<p><strong>7 &#8211; Procure os outros artigos que pretende na mesma loja<\/strong><\/p>\n<p>Se os portes forem gratuitos, pe\u00e7a de tantas lojas lojas quantas quiser. Se n\u00e3o forem, procure os outros artigos na mesma loja de onde j\u00e1 est\u00e1 a encomendar. Se os encontrar, s\u00f3 paga portes uma vez.<\/p>\n<p><strong>8 &#8211; Encontre o pre\u00e7o mais baixo<\/strong><\/p>\n<p>Fa\u00e7a uma pesquisa pelo nome do artigo e encontre o pre\u00e7o mais baixo na listagem. Mas lembre-se de comparar tamb\u00e9m o valor dos portes. Muitas vezes encontra outras lojas que t\u00eam o mesmo artigo em promo\u00e7\u00e3o.<\/p>\n<p><strong>9 &#8211; Verifique a necessidade de escrever ao vendedor<\/strong><\/p>\n<p>Dependendo do artigo, pode encontrar algumas caracter\u00edsticas que precisa de escolher ao encomendar, como c\u00f4r e tamanho.<\/p>\n<p>Mas por vezes, esta op\u00e7\u00e3o n\u00e3o existe. Numa primeira an\u00e1lise parecer\u00e1 que o artigo vir\u00e1 na c\u00f4r da fotografia ou, se apresentado com cores diferentes, poder\u00e1 vir de qualquer uma daquelas cores. O melhor ser\u00e1 n\u00e3o nos pormos a adivinhar porque a coisa pode n\u00e3o correr nada bem.<\/p>\n<p>Leia de novo a descri\u00e7\u00e3o porque muitas vezes est\u00e1 l\u00e1 indicado que ter\u00e1 de enviar mensagem ao vendedor a informar a c\u00f4r que pretende (ou outra caracter\u00edstica) e que se assim n\u00e3o for, receber\u00e1 uma c\u00f4r ao acaso.<\/p>\n<p>Um outro exemplo s\u00e3o artigos electr\u00f3nicos que podem ter ficha para a Europa ou para os EUA. Muitas vezes tem de indicar a ficha que pretende por mensagem, ap\u00f3s a encomenda.<\/p>\n<p><strong>10 &#8211; Use os favoritos para saber das promo\u00e7\u00f5es<\/strong><\/p>\n<p>Ao colocar um artigo na sua lista de favoritos (ou desejos), ser\u00e1 notificado por email e\/ou na aplica\u00e7\u00e3o quando este se encontra em promo\u00e7\u00e3o e por quanto tempo.<\/p>\n<p><strong>11 &#8211; Acompanhe o envio dos artigos encomendados<\/strong><\/p>\n<p>Faz sentido ir acompanhando a entrega das suas encomendas, n\u00e3o s\u00f3 para saber quando chega ou onde se encontra, mas tamb\u00e9m para perceber se houve algum problema.<\/p>\n<p>Por exemplo, o carregador que mencionei anteriormente, foi enviado para o c\u00f3digo postal errado e devolvido \u00e0 China. Se tivesse visto antes, poderia dirigir-me \u00e0 esta\u00e7\u00e3o para onde foi e tentar levantar a encomenda. Como s\u00f3 vi depois de ter sido devolvida, enviei mensagem a perguntar o que tinha acontecido e foi feito um reembolso de imediato.<\/p>\n<p>Se continuasse a aguardar indefinidamente, poderia deixar passar o prazo de protec\u00e7\u00e3o da encomenda e n\u00e3o ser reembolsada.<\/p>\n<p>Alguns sites oferecem esta protec\u00e7\u00e3o, outros talvez n\u00e3o, pleo que ser\u00e1 de interesse ver os termos de utiliza\u00e7\u00e3o do site que usar. Hoje em dia, at\u00e9 o Paypal tem uma protec\u00e7\u00e3o para as compras online &#8211; altera\u00e7\u00e3o recente aos termos de servi\u00e7o, provavelmente impulsionada pela quantidade destas compras nos \u00faltimos tempos.<\/p>\n<p><strong>Geek e AliExpress<\/strong><\/p>\n<p>Quanto \u00e0s aplica\u00e7\u00f5es (sites) que uso:<\/p>\n<ul>\n<li>Geek &#8211; que pertence \u00e0 Wish (\u00e9 capaz de j\u00e1 ter visto algum an\u00fancio no Facebook) e na qual paga sempre portes (embora tenha a 1 ou 2 euros)<\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/09\/ideias_comprach_geek.jpg\" alt=\"\" width=\"500\" height=\"375\" title=\"\"><\/p>\n<ul>\n<li>AliExpress &#8211; talvez o site mais conhecido de compras na China, onde encontra muitos artigos com portes gratuitos<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2015\/09\/ideias_comprasch_ali.jpg\" alt=\"\" width=\"500\" height=\"375\" title=\"\"><\/p>\n<p>E se quiser ver os artigos que recebi da China nestas \u00faltimas encomendas, \u00e9 s\u00f3 espreitar o video abaixo.<\/p>\n<div class=\"ast-oembed-container \" style=\"height: 100%;\"><iframe title=\"Compras da China 2: os recebidos (parte 2 de 2)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5tnLrRBcY4o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>[bctt tweet=&#8221;J\u00e1 comprou alguma coisa da China?&#8221;]<\/p>\n<p><strong>Tem alguma dica para acrescentar?<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabe aqueles sites de produtos que v\u00eam da China, com pre\u00e7os mais curtos que a mini saia? Hoje trago 11 dicas para partilhar consigo sobre como pode (tamb\u00e9m) poupar nestas encomendas. Tanto podemos poupar reduzindo o pre\u00e7o de custo na hora da compra, quanto reduzindo custos (e chatices) a curto e m\u00e9dio prazo. Refiro-me a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[110],"tags":[113,4,112],"class_list":["post-3800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poupanca","tag-compras-da-china","tag-dicas","tag-poupanca"],"_links":{"self":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/3800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/comments?post=3800"}],"version-history":[{"count":0,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/3800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media\/9467"}],"wp:attachment":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media?parent=3800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/categories?post=3800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/tags?post=3800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}