{"id":189,"date":"2012-07-27T21:10:00","date_gmt":"2012-07-27T21:10:00","guid":{"rendered":"https:\/\/ideiasdafia.pt\/?p=189"},"modified":"2019-09-02T17:43:43","modified_gmt":"2019-09-02T17:43:43","slug":"manga-tatuada","status":"publish","type":"post","link":"https:\/\/ideiasdafia.pt\/en\/manga-tatuada\/","title":{"rendered":"Manga tatuada"},"content":{"rendered":"<p>Viva!<\/p>\n\n\n\n<p>Se leu o post sobre o <a href=\"https:\/\/ideiasdafia.pt\/en\/?p=191\">DIY falhado<\/a> do outro dia, percebeu que estava de volta de um projecto de tatuagem tempor\u00e1ria para uma sess\u00e3o fotogr\u00e1fica. Claro que se ficasse bem, poderia us\u00e1-la uma vez por outra&#8230;<\/p>\n\n\n\n<p>Ent\u00e3o, a primeira tentativa foi completamente ao lado, mas ao perceber que nem todas as tintas tinham &#8220;esborratado&#8221;, voltei \u00e0 carga.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00378.jpg\" alt=\"\" class=\"wp-image-7743\" width=\"800\" height=\"600\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00378.jpg 800w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00378-300x225.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00378-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Podia ter ficado melhor, o tra\u00e7o n\u00e3o ficou perfeito&#8230; mas que sorte a de n\u00e3o ser perfeccionista! (n\u00e3o, ainda n\u00e3o aderi ao acordo ortogr\u00e1fico!)<br>Queria tamb\u00e9m que a manga ficasse mais &#8220;cheia&#8221;, mas tinha de continuar a inspirar-me em pormenores para a preencher!<\/p>\n\n\n\n<p>Material necess\u00e1rio:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>meias curtas, cor de pele<\/li><li>canetas permanentes e n\u00e3o permanentes (vulgo canetas de acetato)<\/li><li>desenho a copiar<\/li><li>cart\u00e3o<\/li><\/ul>\n\n\n\n<p>Depois de ter os desenhos escolhidos e impressos no tamanho que pretendia, coloquei uma meia num cart\u00e3o (podem sempre pedir um bra\u00e7o emprestado, mas conv\u00e9m proteg\u00ea-lo por dentro da meia &#8211; diria que um pl\u00e1stico seria uma boa ideia) e o desenho no local onde pretendia copi\u00e1-lo (por dentro da meia e preso no cart\u00e3o com fita-cola).<\/p>\n\n\n\n<p>Depois delineei o desenho com as cores escolhidas; procurei escolher uma cor aproximada \u00e0 cor do enchimento dessa parte do desenho. Para encher uma zona de cor, pintei apenas um pouco no interior, junto ao contorno, e &#8220;puxei&#8221; a cor com um cotonete humedecido em \u00e1lcool para o interior do desenho. Isto permite ter gradientes de cor, imitando a tatuagem na pele.<\/p>\n\n\n\n<p>Usei dois tipos de caneta (permanente e n\u00e3o permanente) apenas para aproveitar as cores que tinha de umas e de outras. A diferen\u00e7a \u00e9 que a permanente \u00e9 \u00e0 prova de \u00e1gua e bem mais dif\u00edcil de tirar.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00381.jpg\" alt=\"\" class=\"wp-image-7744\" width=\"535\" height=\"359\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00381.jpg 800w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00381-300x202.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00381-768x517.jpg 768w\" sizes=\"(max-width: 535px) 100vw, 535px\" \/><\/figure><\/div>\n\n\n\n<p>At\u00e9 acho que imita bem o suficiente para fotografia. Mas ainda tem muito &#8220;espa\u00e7o em branco&#8221;! No entanto,&nbsp;quando a dava &#8211; para j\u00e1 &#8211; como terminada, eis que chegou o correio com uma encomenda para mim! \ud83d\ude00 (\u00f3 p&#8217;r\u00f3 meu <em>big smile<\/em>!)<\/p>\n\n\n\n<p>Chegou a manga tatuada que tinha encomendado na semana anterior no site alem\u00e3o <a rel=\"noreferrer noopener\" href=\"http:\/\/www.wildrosetattooshirts.com\/\" target=\"_blank\">Wild Rose Tattoo Clothing<\/a>. Foi a primeira vez que lhes encomendei algo, mas considerava a resposta deles muito r\u00e1pida e cordial e estou muito contente. Ainda n\u00e3o a usei, mas j\u00e1 considero ter valido a compra.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00385.jpg\" alt=\"\" class=\"wp-image-7745\" width=\"533\" height=\"710\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00385.jpg 600w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/DSC00385-225x300.jpg 225w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/figure><\/div>\n\n\n\n<p>Claro que o resultado \u00e9 bem diferente, n\u00e3o \u00e9?! <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/mangas.jpg\" alt=\"\" class=\"wp-image-7759\" width=\"536\" height=\"445\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/mangas.jpg 800w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/mangas-300x249.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/07\/mangas-768x637.jpg 768w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/figure><\/div>\n\n\n\n<p>De qualquer forma, d\u00e1 para tirar ideias e brincar um pouco, certo?<\/p>\n\n\n\n<p>O \u00fanico problema que acabei por n\u00e3o solucionar na manga caseira foi o facto da meia enrolar muito facilmente na zona onde \u00e9 cortada, mas parece-me que pode ser resolvido, mergulhando essa &#8220;ponta&#8221; em maizena e \u00e1gua (goma caseira). No post sobre as <a href=\"https:\/\/ideiasdafia.pt\/en\/?p=192\">penas DIY<\/a> partilho a forma de usar esta mistura para manter a forma do fio\/tecido.<\/p>\n\n\n\n<p>Entretanto, fiz um pequeno video para ilustrar este DIY.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Temporary tattoo sleeve DIY\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/JeajfEaOJbQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>T\u00e1 a\u00ed a dica.<\/p>\n\n\n\n<p>Bjocas estilo&nbsp;<em>bad ass<\/em>,<br>Sofia \ud83d\ude42<\/p>","protected":false},"excerpt":{"rendered":"<p>Viva! Se leu o post sobre o DIY falhado do outro dia, percebeu que estava de volta de um projecto de tatuagem tempor\u00e1ria para uma sess\u00e3o fotogr\u00e1fica. Claro que se ficasse bem, poderia us\u00e1-la uma vez por outra&#8230; Ent\u00e3o, a primeira tentativa foi completamente ao lado, mas ao perceber que nem todas as tintas tinham [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[45],"tags":[4,5,6,25,299,10,11],"class_list":["post-189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","tag-dicas","tag-fotografia","tag-inspiracao","tag-manga-tatuada","tag-tatuagem","tag-tutorial","tag-video"],"_links":{"self":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/comments?post=189"}],"version-history":[{"count":0,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media\/7758"}],"wp:attachment":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media?parent=189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/categories?post=189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/tags?post=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}