{"id":122,"date":"2012-12-08T15:38:00","date_gmt":"2012-12-08T15:38:00","guid":{"rendered":"https:\/\/ideiasdafia.pt\/?p=122"},"modified":"2019-09-02T17:40:20","modified_gmt":"2019-09-02T17:40:20","slug":"frasquinhos-doces","status":"publish","type":"post","link":"https:\/\/ideiasdafia.pt\/en\/frasquinhos-doces\/","title":{"rendered":"Frasquinhos doces"},"content":{"rendered":"<p>Viva!<\/p>\n\n\n\n<p>Trago uma ideia para uma uma boa dose de mimo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_01.jpg\" alt=\"\" class=\"wp-image-8398\" width=\"800\" height=\"451\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_01.jpg 800w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_01-300x169.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_01-768x433.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>E t\u00e3o simples que \u00e9! Quer saber como fiz?<br>S\u00f3 comprei os doces&#8230;<\/p>\n\n\n\n<p>1. Peguei os vidrinhos de uma sobremesa de compra que tinha por aqui, Depois de lavados e prontos a usar,<\/p>\n\n\n\n<p>2. Enchi com passas cobertas de chocolate.<\/p>\n\n\n\n<p>3. Aproveitei amostras de tecidos que tinha por aqui, que cortei em quadrado.<\/p>\n\n\n\n<p>4. Coloquei na boca do frasco e atei uma fitinha num la\u00e7arote.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_02.jpg\" alt=\"\" class=\"wp-image-8399\" width=\"800\" height=\"596\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_02.jpg 800w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_02-300x224.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_02-768x572.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Tamb\u00e9m ficava bem com os tecidos em redondo, mas gosto de ver as pontas e tamb\u00e9m quis aproveitar o recorte do tecido.<\/p>\n\n\n\n<p>Ficaram uma gracinha!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_03.jpg\" alt=\"\" class=\"wp-image-8400\" width=\"800\" height=\"532\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_03.jpg 800w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_03-300x200.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2012\/12\/frasquinhos_doces_03-768x511.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Gostou?<br>N\u00e3o \u00e9 nada de novo, mas \u00e9 simples e um mimo sabe sempre bem! \ud83d\ude09<br>Se n\u00e3o souber o tempo que levar para dar a dose de mimo a algu\u00e9m, talvez seja melhor usar um peda\u00e7o de pl\u00e1stico de cozinha por baixo do tecido para preservar os doces do ar. Saltei esse passo nos meus, mas nos pr\u00f3ximos coloco!<\/p>\n\n\n\n<p>H\u00e1 tantas ideias giras para reaproveitar frascos e latinhas para as doses de mimo que dif\u00edcil fica realizar todas! \ud83d\ude42<\/p>\n\n\n\n<p>Beijocas mimosas!<\/p>","protected":false},"excerpt":{"rendered":"<p>Viva! Trago uma ideia para uma uma boa dose de mimo. E t\u00e3o simples que \u00e9! Quer saber como fiz?S\u00f3 comprei os doces&#8230; 1. Peguei os vidrinhos de uma sobremesa de compra que tinha por aqui, Depois de lavados e prontos a usar, 2. Enchi com passas cobertas de chocolate. 3. Aproveitei amostras de tecidos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[45],"tags":[4,6,7,8],"class_list":["post-122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","tag-dicas","tag-inspiracao","tag-oferta","tag-reciclados"],"_links":{"self":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":0,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media\/8401"}],"wp:attachment":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media?parent=122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/categories?post=122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/tags?post=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}