{"id":10844,"date":"2020-03-18T11:53:00","date_gmt":"2020-03-18T11:53:00","guid":{"rendered":"https:\/\/ideiasdafia.pt\/?p=10844"},"modified":"2020-03-18T21:57:22","modified_gmt":"2020-03-18T21:57:22","slug":"8-ideias-para-entreter-as-criancas-em-casa","status":"publish","type":"post","link":"https:\/\/ideiasdafia.pt\/en\/8-ideias-para-entreter-as-criancas-em-casa\/","title":{"rendered":"8 Ideias para entreter as crian\u00e7as em casa"},"content":{"rendered":"<p>Ontem <a href=\"https:\/\/ideiasdafia.pt\/en\/2020\/03\/17\/o-que-fazer-de-quarentena\/\" class=\"rank-math-link\">escrevia <\/a>sobre este per\u00edodo de quarentena devido ao COVID-19 e lembrei-me que poderia partilhar contigo algumas ideias mais pr\u00e1ticas para aproveitar este recolhimento &#8220;for\u00e7ado&#8221; de uma forma prazerosa e saud\u00e1vel.<\/p>\n\n\n\n<p>Ent\u00e3o lembrei-me de separar por temas e as ideias de hoje s\u00e3o voltadas para os mais pequenos.<\/p>\n\n\n\n<p><strong>1. Pote de ideias<\/strong><\/p>\n\n\n\n<p>Uma ideia que eu acho sempre boa \u00e9 a de reunir uma s\u00e9rie de ideias entre todos e criar um potinho onde colocar todas elas e tirar uma \u00e0 sorte nos momentos mais aborrecidos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-7-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10845\" width=\"400\" height=\"346\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-7-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-7-ideias-da-fia-300x260.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>A primeira actividade \u00e9 a de construir esta ferramenta, claro. <\/p>\n\n\n\n<p>Esta \u00e9 uma ideia que serve para os exerc\u00edcios de escrita ou outros estudos, mas tamb\u00e9m para as brincadeiras ou outro tipo de tarefas. Mas tamb\u00e9m pode ser tudo misturado.<\/p>\n\n\n\n<p>Mas em vez de um pote (ou frasco), tamb\u00e9m pode ser constru\u00eddo uma esp\u00e9cie de dado para o mesmo efeito.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-3-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10850\" width=\"300\" height=\"300\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-3-ideias-da-fia.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-3-ideias-da-fia-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>S\u00f3 tem um n\u00famero mais limitado de op\u00e7\u00f5es.<\/p>\n\n\n\n<p><strong>2. Tampas<\/strong> <strong>animadas<\/strong><\/p>\n\n\n\n<p>Aproveitando as tampas de frascos e garrafas, podemos decorar ou pintar joaninhas nelas. Ou em pedras, j\u00e1 agora.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-4-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10846\" width=\"214\" height=\"320\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-4-ideias-da-fia.jpg 214w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-4-ideias-da-fia-201x300.jpg 201w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/><\/figure><\/div>\n\n\n\n<p><strong>3. Labirinto caseiro<\/strong><\/p>\n\n\n\n<p>Quando eu era pequena fazia muitos labirintos diferentes em placas de Lego e com pe\u00e7as de Lego e berlindes. Era um passatempo que eu e o meu irm\u00e3o t\u00ednhamos. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-5-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10847\" width=\"400\" height=\"267\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-5-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-5-ideias-da-fia-300x200.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>Por vezes, d\u00e1vamos at\u00e9 um passo mais \u00e0 frente e recri\u00e1vamos uma esp\u00e9cie de <em>flippers<\/em> da mesma forma.<\/p>\n\n\n\n<p>No entanto, nem s\u00e3o precisas as pe\u00e7as de Lego, pois podemos usar um tabuleiro ou uma tampa de caixa de sapatos e cordas que colamos no fundo, ou palhinhas (canudos).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-10-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10848\" width=\"400\" height=\"400\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-10-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-10-ideias-da-fia-300x300.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-10-ideias-da-fia-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p><strong>4. Constru\u00e7\u00e3o de hist\u00f3rias<\/strong><\/p>\n\n\n\n<p>Sou suspeita porque <a href=\"https:\/\/ideiasdafia.pt\/en\/2012\/05\/19\/semeando-sorrisos-pela-semana\/\" class=\"rank-math-link\">gosto de pintar pedras<\/a>, mas adoro esta ideia: pintar ou colar num conjunto de pedras elementos com que podem ser criadas hist\u00f3rias. Podem ser imagens de transportes, personagens, estado do tempo, animais, lugares, casa, parque, cinema, etc.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-2-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10849\" width=\"266\" height=\"400\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-2-ideias-da-fia.jpg 266w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-2-ideias-da-fia-200x300.jpg 200w\" sizes=\"(max-width: 266px) 100vw, 266px\" \/><\/figure><\/div>\n\n\n\n<p>Depois \u00e9 ir tirando as pedrinhas e ir construindo uma hist\u00f3ria. Adoro!<\/p>\n\n\n\n<p><strong>5. Roda da sorte<\/strong><\/p>\n\n\n\n<p>Esta ideia \u00e9 muito parecida com a primeira, mas tem outro tipo de potencial.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-8-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10851\" width=\"400\" height=\"533\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-8-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-8-ideias-da-fia-225x300.jpg 225w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>\u00c9 uma roda de possibilidades. Serve para atividades, exerc\u00edcios, personagens a encarnar no dia, hist\u00f3ria a representar, tema do dia, etc.<\/p>\n\n\n\n<p>Pode ser constru\u00edda em cart\u00e3o e colocada em cima de <em>fidget spinner<\/em> ou colocar este por cima com uma seta numa da pontas. (deu para perceber?) E \u00e9 s\u00f3 rodar.<\/p>\n\n\n\n<p>Mas tamb\u00e9m pode ser feito \u00e0 moda antiga: com uma tacha.<\/p>\n\n\n\n<p><strong>6. Brinquedos de cart\u00e3o<\/strong><\/p>\n\n\n\n<p>H\u00e1 tantas possibilidades nesta categoria&#8230;<\/p>\n\n\n\n<p>Deixo antes duas, que achei at\u00e9 meio sofisticadas. Uma lavagem autom\u00e1tica para os carrinhos&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-1-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10852\" width=\"400\" height=\"572\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-1-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-1-ideias-da-fia-210x300.jpg 210w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>E um posto de abastecimento.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-9-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10853\" width=\"400\" height=\"539\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-9-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-9-ideias-da-fia-223x300.jpg 223w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>Mas quando era pequena, fazia desde uma casa (com uma caixa de frigor\u00edfico) at\u00e9 uma mesa para fazer r\u00e1dio (com tape, leitor de vinil, microfone e muitos bot\u00f5es).<\/p>\n\n\n\n<p><strong>7. Jogo educativo<\/strong><\/p>\n\n\n\n<p>H\u00e1 tamb\u00e9m um sem n\u00famero de jogos educativos que podem ser constru\u00eddos em casa. Fica uma ideia.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-11-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10854\" width=\"400\" height=\"313\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-11-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-11-ideias-da-fia-300x235.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p><strong>8. Animais de l\u00e3<\/strong><\/p>\n\n\n\n<p>Esta \u00e9 uma ideia muito fofa. Podemos fazer c\u00e3ezinhos a partir de pequenas garrafas, tubos de papel higi\u00e9nico ou tampas de embalagem.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Como fazer cachorrinha de l\u00e3 com tampinha de desodorante | Pricity\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/YXkUDxFh-1s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-6-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10855\" width=\"400\" height=\"400\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-6-ideias-da-fia.jpg 400w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-6-ideias-da-fia-300x300.jpg 300w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-6-ideias-da-fia-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>Ou coelhinhos para a P\u00e1scoa&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"\u041c\u0418\u041b\u0410\u0428\u041a\u0410 \u041a\u0420\u041e\u041b\u0418\u041a \u0418\u0417 \u041f\u041e\u041c\u041f\u041e\u041d\u041e\u0412 (\u043c\u0430\u0441\u0442\u0435\u0440-\u043a\u043b\u0430\u0441\u0441) \/ DIY NataliDoma\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/PNLErBL4MYg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Cavalos&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-12-ideias-da-fia.jpg\" alt=\"\" class=\"wp-image-10856\" width=\"290\" height=\"356\" title=\"\" srcset=\"https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-12-ideias-da-fia.jpg 290w, https:\/\/ideiasdafia.pt\/wp-content\/uploads\/2020\/03\/quarentena-ideias-brincadeiras-12-ideias-da-fia-244x300.jpg 244w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/figure><\/div>\n\n\n\n<p>Entre muitos outros que facilmente encontras pelo YouTube ou no Pinterest.<\/p>\n\n\n\n<p>Claro que h\u00e1 sempre os jogos de tabuleiro que est\u00e3o arrumados l\u00e1 no fundinho do ba\u00fa, os jogos de cartas e tantas outras brincadeiras que nem precisam de materiais. <\/p>\n\n\n\n<p>Estas s\u00e3o as ideias de hoje. <strong>Qual a tua preferida?<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Uma ideia que eu acho sempre boa \u00e9 a de reunir uma s\u00e9rie de ideias entre todos e criar um potinho onde colocar todas elas e tirar uma \u00e0 sorte nos momentos mais aborrecidos.<\/p>","protected":false},"author":1,"featured_media":10854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[45],"tags":[115,64,306,304],"class_list":["post-10844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","tag-brincadeira","tag-criancas","tag-diy","tag-quarentena"],"_links":{"self":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/10844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/comments?post=10844"}],"version-history":[{"count":0,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/posts\/10844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media\/10854"}],"wp:attachment":[{"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/media?parent=10844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/categories?post=10844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ideiasdafia.pt\/en\/wp-json\/wp\/v2\/tags?post=10844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}